{"id":63484,"date":"2026-05-12T10:44:15","date_gmt":"2026-05-12T09:44:15","guid":{"rendered":"https:\/\/churchtools.academy\/?post_type=changelog&#038;p=63484"},"modified":"2026-05-12T11:02:37","modified_gmt":"2026-05-12T10:02:37","slug":"web-v3-132-1","status":"publish","type":"changelog","link":"https:\/\/churchtools.academy\/de\/changelog\/web-v3-132-1\/","title":{"rendered":"Web v3.132.1"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"behobenefehler\">Behobene Fehler<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Personen<\/strong>\n<ul class=\"wp-block-list\">\n<li>Beim Bearbeiten des Benutzernamens (oder anderer Felder im Bereich Adresse) wurden die E-Mail-Adressen einer Person gel\u00f6scht.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Gruppen<\/strong>\n<ul class=\"wp-block-list\">\n<li>Routinen bleiben beim \u00c4ndern des Gruppentyps erhalten.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Sync<\/strong>\n<ul class=\"wp-block-list\">\n<li>Die Filterleiste in den Protokollen funktioniert wieder korrekt.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"template":"","plattform":[687],"class_list":["post-63484","changelog","type-changelog","status-publish","hentry","plattform-web"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","pp_force_visibility":null,"pp_subpost_visibility":null,"pp_inherited_force_visibility":null,"pp_inherited_subpost_visibility":null,"acf":{"version":"3.132.1"},"_links":{"self":[{"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/changelog\/63484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/changelog"}],"about":[{"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/types\/changelog"}],"version-history":[{"count":3,"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/changelog\/63484\/revisions"}],"predecessor-version":[{"id":63501,"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/changelog\/63484\/revisions\/63501"}],"wp:attachment":[{"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/media?parent=63484"}],"wp:term":[{"taxonomy":"plattform","embeddable":true,"href":"https:\/\/churchtools.academy\/de\/wp-json\/wp\/v2\/plattform?post=63484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}